{"id":4163,"date":"2021-05-25T07:17:01","date_gmt":"2021-05-25T07:17:01","guid":{"rendered":"https:\/\/meroil.es\/?post_type=product&#038;p=4163"},"modified":"2026-04-18T10:26:39","modified_gmt":"2026-04-18T09:26:39","slug":"bandolera-documentos","status":"publish","type":"product","link":"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/","title":{"rendered":"BANDOLERA DOCUMENTOS"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>&#8211; Portadocumentos con solapa de cierre de velcro en poli\u00e9ster 600D y con franja frontal reflectante.<br \/>\n&#8211; Con asas reforzada a juego, cinta bandolera ajustable y compartimentos interiores con fundas para bol\u00edgrafos y smartphone.<br \/>\n&#8211; Medidas y Peso Art\u00edculo: 24 x 32 x 4 cm | 155 gr.<\/p>\n","protected":false},"featured_media":5937,"template":"","meta":[],"product_brand":[],"product_cat":[32],"product_tag":[],"class_list":{"0":"post-4163","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-viaje","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BANDOLERA DOCUMENTOS - Meroil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BANDOLERA DOCUMENTOS - Meroil\" \/>\n<meta property=\"og:description\" content=\"- Portadocumentos con solapa de cierre de velcro en poli\u00e9ster 600D y con franja frontal reflectante. - Con asas reforzada a juego, cinta bandolera ajustable y compartimentos interiores con fundas para bol\u00edgrafos y smartphone. - Medidas y Peso Art\u00edculo: 24 x 32 x 4 cm | 155 gr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/\" \/>\n<meta property=\"og:site_name\" content=\"Meroil\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-18T09:26:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.meroil.es\/wp-content\/uploads\/2021\/05\/REF_9309.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/catalogo\\\/viaje\\\/bandolera-documentos\\\/\",\"url\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/catalogo\\\/viaje\\\/bandolera-documentos\\\/\",\"name\":\"BANDOLERA DOCUMENTOS - Meroil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/catalogo\\\/viaje\\\/bandolera-documentos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/catalogo\\\/viaje\\\/bandolera-documentos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meroil.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/REF_9309.jpg\",\"datePublished\":\"2021-05-25T07:17:01+00:00\",\"dateModified\":\"2026-04-18T09:26:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/catalogo\\\/viaje\\\/bandolera-documentos\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meroil.es\\\/ca\\\/catalogo\\\/viaje\\\/bandolera-documentos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/catalogo\\\/viaje\\\/bandolera-documentos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meroil.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/REF_9309.jpg\",\"contentUrl\":\"https:\\\/\\\/www.meroil.es\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/REF_9309.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/catalogo\\\/viaje\\\/bandolera-documentos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logo de puntos\",\"item\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BANDOLERA DOCUMENTOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/\",\"name\":\"Meroil\",\"description\":\"Estaciones de proximidad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meroil.es\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BANDOLERA DOCUMENTOS - Meroil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/","og_locale":"ca_ES","og_type":"article","og_title":"BANDOLERA DOCUMENTOS - Meroil","og_description":"- Portadocumentos con solapa de cierre de velcro en poli\u00e9ster 600D y con franja frontal reflectante. - Con asas reforzada a juego, cinta bandolera ajustable y compartimentos interiores con fundas para bol\u00edgrafos y smartphone. - Medidas y Peso Art\u00edculo: 24 x 32 x 4 cm | 155 gr.","og_url":"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/","og_site_name":"Meroil","article_modified_time":"2026-04-18T09:26:39+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.meroil.es\/wp-content\/uploads\/2021\/05\/REF_9309.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/","url":"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/","name":"BANDOLERA DOCUMENTOS - Meroil","isPartOf":{"@id":"https:\/\/www.meroil.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/#primaryimage"},"image":{"@id":"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meroil.es\/wp-content\/uploads\/2021\/05\/REF_9309.jpg","datePublished":"2021-05-25T07:17:01+00:00","dateModified":"2026-04-18T09:26:39+00:00","breadcrumb":{"@id":"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/#primaryimage","url":"https:\/\/www.meroil.es\/wp-content\/uploads\/2021\/05\/REF_9309.jpg","contentUrl":"https:\/\/www.meroil.es\/wp-content\/uploads\/2021\/05\/REF_9309.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.meroil.es\/ca\/catalogo\/viaje\/bandolera-documentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.meroil.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logo de puntos","item":"https:\/\/www.meroil.es\/ca\/catalogo\/"},{"@type":"ListItem","position":3,"name":"BANDOLERA DOCUMENTOS"}]},{"@type":"WebSite","@id":"https:\/\/www.meroil.es\/ca\/#website","url":"https:\/\/www.meroil.es\/ca\/","name":"Meroil","description":"Estaciones de proximidad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meroil.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/www.meroil.es\/ca\/wp-json\/wp\/v2\/product\/4163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meroil.es\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.meroil.es\/ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.meroil.es\/ca\/wp-json\/wp\/v2\/media\/5937"}],"wp:attachment":[{"href":"https:\/\/www.meroil.es\/ca\/wp-json\/wp\/v2\/media?parent=4163"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.meroil.es\/ca\/wp-json\/wp\/v2\/product_brand?post=4163"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.meroil.es\/ca\/wp-json\/wp\/v2\/product_cat?post=4163"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.meroil.es\/ca\/wp-json\/wp\/v2\/product_tag?post=4163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}